{"id":96,"count":177,"description":"","link":"https:\/\/www.fajarpaper.com\/category\/article\/press-releases\/","name":"Press Releases","slug":"press-releases","taxonomy":"category","parent":95,"meta":[],"_links":{"self":[{"href":"https:\/\/www.fajarpaper.com\/wp-json\/wp\/v2\/categories\/96","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fajarpaper.com\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.fajarpaper.com\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.fajarpaper.com\/wp-json\/wp\/v2\/categories\/95"}],"wp:post_type":[{"href":"https:\/\/www.fajarpaper.com\/wp-json\/wp\/v2\/posts?categories=96"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}