{"id":23570,"date":"2021-02-23T17:17:22","date_gmt":"2021-02-23T10:17:22","guid":{"rendered":"https:\/\/fp.konsep.com\/contact-us-whistle-blower\/"},"modified":"2021-02-23T17:18:48","modified_gmt":"2021-02-23T10:18:48","slug":"contact-us-whistle-blower","status":"publish","type":"page","link":"https:\/\/www.fajarpaper.com\/contact-us-whistle-blower\/?lang=id","title":{"rendered":"Contact Us : Whistle Blower"},"content":{"rendered":"<p>[vc_row][vc_column]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f23566-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"23566\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/wp-json\/wp\/v2\/pages\/23570#wpcf7-f23566-o1\" method=\"post\" class=\"wpcf7-form init bottom-space career-form\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"23566\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f23566-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<h3>Whistle <strong>Blower<\/strong>\n<\/h3>\n<div class=\"column dt-sc-one-column\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"names\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name *\" value=\"\" type=\"text\" name=\"names\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"column dt-sc-one-half first\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"tel\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Telephone *\" value=\"\" type=\"tel\" name=\"tel\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"column dt-sc-one-half\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email *\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"column dt-sc-one-column\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Subject *\" value=\"\" type=\"text\" name=\"subject\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Message *\" name=\"message\"><\/textarea><\/span>\n\t<\/p>\n\t<div class=\"dt-sc-clear\">\n\t<\/div>\n\t<div class=\"dt-sc-hr-top-20\">\n\t<\/div>\n<\/div>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Submit\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<div id=\"1557836120454-647627d7-abc7\" class=\"dt-sc-empty-space\"><\/div>[\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-23570","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.fajarpaper.com\/wp-json\/wp\/v2\/pages\/23570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fajarpaper.com\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fajarpaper.com\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fajarpaper.com\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fajarpaper.com\/wp-json\/wp\/v2\/comments?post=23570"}],"version-history":[{"count":1,"href":"https:\/\/www.fajarpaper.com\/wp-json\/wp\/v2\/pages\/23570\/revisions"}],"predecessor-version":[{"id":23571,"href":"https:\/\/www.fajarpaper.com\/wp-json\/wp\/v2\/pages\/23570\/revisions\/23571"}],"wp:attachment":[{"href":"https:\/\/www.fajarpaper.com\/wp-json\/wp\/v2\/media?parent=23570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}